{"id":18213,"date":"2023-07-07T02:25:47","date_gmt":"2023-07-07T02:25:47","guid":{"rendered":"https:\/\/oudianvalve.com\/?p=18213"},"modified":"2023-07-07T02:25:47","modified_gmt":"2023-07-07T02:25:47","slug":"300lb-stainless-steel-globe-valve","status":"publish","type":"post","link":"https:\/\/oudianvalve.com\/it\/2023\/07\/300lb-stainless-steel-globe-valve\/","title":{"rendered":"Valvola a globo in acciaio inossidabile da 300 libbre"},"content":{"rendered":"<p><strong>Descrizioni<\/strong><br \/>\nNorma di progettazione: ASME B16.34<br \/>\nClassificazione pressione-temperatura: ASME B16.34<br \/>\nIntervallo di dimensioni: da 2&quot; a 48&quot;<br \/>\nIntervallo di pressione: classe da 150 a 2500<br \/>\nConnessioni terminali: RF flangiate, RTJ, saldate di testa<br \/>\nDimensioni estremit\u00e0 flangiate: ASME B16.5 (\u226424\u201d), ASME B16.47 Serie A o B (&gt;24\u201d)<br \/>\nDimensioni estremit\u00e0 saldatura di testa: ASME B16.25 faccia a faccia<br \/>\nDimensioni faccia a faccia: ASME B16.10<br \/>\nIspezione e test: API 598<br \/>\nMateriali del corpo: ASTM A351 CF8, ASTM A351 CF8M, ASTM A351 CF3M, ASTM A351 CF8C<br \/>\nCN3MN, CK3MCUN, CN7M, ASTM A890 4A(CD3MN), ASTM A890 5A(CE3MN),<br \/>\nASTM A890 6A(CD3MWCuN)<br \/>\nASTM B148 C95800, ASTM B148 C95500.<br \/>\nMateriali di imballaggio: PTFE, PPL<\/p>\n<p>300LB \u2013 2\u2033 25 unit\u00e0<\/p>\n<p>Se sei interessato alle valvole di cui sopra, contattaci liberamente tramite emailsales@oudianvalve.com<\/p>\n<p>Si prega di trovare le immagini delle valvole allegate.<\/p>\n<p>CINA OUDIAN VALVOLA CO., LTD<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18244 size-full\" src=\"https:\/\/oudianvalve.com\/wp-content\/uploads\/2023\/07\/300lb-stainless-steel-globe-valve.jpg\" alt=\"300LB Stainless steel Globe Valve\" width=\"1280\" height=\"1707\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18245 size-full\" src=\"https:\/\/oudianvalve.com\/wp-content\/uploads\/2023\/07\/300lb-stainless-steel-globe-valve-1.jpg\" alt=\"Stainless Steel Globe Valve\" width=\"1280\" height=\"1707\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-18246 size-full\" src=\"https:\/\/oudianvalve.com\/wp-content\/uploads\/2023\/07\/300lb-stainless-steel-globe-valve-2.jpg\" alt=\"304 Stainless Steel Globe Valve\" width=\"1280\" height=\"1707\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Descriptions Design Standard: ASME B16.34 Pressure-temperature Ratings: ASME B16.34 Size Range: 2\u201d to 48\u201d Pressure Range: Class 150 to 2500 End Connections: Flanged RF, RTJ, Butt Weld Flanged End Dimensions: ASME B16.5 (\u226424\u201d), ASME B16.47 Series A or B (&gt;24\u201d) Butt Weld End Dimensions: ASME B16.25 Face to Face Face to Face Dimensions: ASME B16.10 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[302,301,300,303],"class_list":["post-18213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industry-news","tag-2-inch-300lb-stainless-steel-globe-valve","tag-300lb-304-stainless-steel-globe-valve","tag-300lb-stainless-steel-globe-valve","tag-300lb-stainless-steel-globe-valve-supplier"],"jetpack_featured_media_url":"https:\/\/oudianvalve.com\/wp-content\/uploads\/2023\/07\/300lb-stainless-steel-globe-valve-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/posts\/18213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/comments?post=18213"}],"version-history":[{"count":1,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/posts\/18213\/revisions"}],"predecessor-version":[{"id":18247,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/posts\/18213\/revisions\/18247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/media\/18245"}],"wp:attachment":[{"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/media?parent=18213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/categories?post=18213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oudianvalve.com\/it\/wp-json\/wp\/v2\/tags?post=18213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}