{"id":18142,"date":"2023-06-21T04:07:08","date_gmt":"2023-06-21T04:07:08","guid":{"rendered":"https:\/\/oudianvalve.com\/?post_type=product&#038;p=18142"},"modified":"2023-06-21T04:55:59","modified_gmt":"2023-06-21T04:55:59","slug":"cn7m-gate-valve-3-inch-api-600-150-lb-rf","status":"publish","type":"product","link":"https:\/\/oudianvalve.com\/es\/products\/gate-valves\/cn7m-gate-valve-3-inch-api-600-150-lb-rf\/","title":{"rendered":"V\u00e1lvula de compuerta CN7M, 3 pulgadas, API 600, 150 LB, RF"},"content":{"rendered":"<p>Est\u00e1ndar de dise\u00f1o: API 600<br \/>\nClasificaciones de presi\u00f3n y temperatura: ASME B16.34<br \/>\nRango de tama\u00f1os: 2\u201d a 48\u201d<br \/>\nRango de presi\u00f3n: Clase 150 a 2500<br \/>\nConexiones finales: RF con bridas, RTJ, soldadura a tope<br \/>\nDimensiones del extremo bridado: ASME B16.5 (\u226424\u201d), ASME B16.47 Serie A o B (&gt;24\u201d)<br \/>\nDimensiones del extremo de soldadura a tope: ASME B16.25 cara a cara<br \/>\nDimensiones cara a cara: ASME B16.10<br \/>\nInspecci\u00f3n y pruebas: API 598<br \/>\nMateriales del cuerpo: ASTM A351 CF8, ASTM A351 CF8M, ASTM A351 CF3M, ASTM A351 CF8C <a id=\"set-post-thumbnail\" class=\"thickbox\" href=\"https:\/\/oudianvalve.com\/wp-admin\/media-upload.php?post_id=18142&amp;type=image&amp;TB_iframe=1\">Establecer imagen del producto<\/a><br \/>\nCN3MN, CK3MCUN, CN7M, ASTM A890 4A(CD3MN), ASTM A890 5A(CE3MN),<br \/>\nASTM A890 6A(CD3MWCuN)<br \/>\nASTM B148 C95800, ASTM B148 C95500.<br \/>\nMateriales de embalaje: Ptfe, PPL, grafito, grafito con alambre de inconel<\/p>","protected":false},"excerpt":{"rendered":"<p>CN7M es una aleaci\u00f3n a base de n\u00edquel con norma de ejecuci\u00f3n ASTM A351\/351M-2018, espec\u00edficamente formulada para fundici\u00f3n de acero inoxidable austen\u00edtico. Su composici\u00f3n qu\u00edmica principal es muy similar a la aleaci\u00f3n 20 UNS NO8020, y tambi\u00e9n se la conoce aproximadamente como aleaci\u00f3n 20 en China. Tiene buena resistencia a la corrosi\u00f3n y es adecuado para medios como \u00e1cido sulf\u00farico, \u00e1cido n\u00edtrico, \u00e1cido clorh\u00eddrico, sulfuro de hidr\u00f3geno, \u00e1cido org\u00e1nico, soluci\u00f3n alcalina, etc.<\/p>\n<ul>\n<li>Tallo ascendente<\/li>\n<li>Asiento de v\u00e1lvula integral\/asientos soldados con sello<\/li>\n<li>Resaltes para grifos y bypass<\/li>\n<li>Guiado completo, cu\u00f1a<\/li>\n<li>Emisiones fugitivas probadas<\/li>\n<li>NACE MR0175 (opcional)<\/li>\n<\/ul>","protected":false},"featured_media":18143,"template":"","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[81],"product_tag":[206,204,205,203,207],"class_list":{"0":"post-18142","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-gate-valves","7":"product_tag-150lb-cn7m-gate-valve","8":"product_tag-3-inch-cn7m-gate-valve","9":"product_tag-api600-cn7m-gate-valve","10":"product_tag-cn7m-gate-valve","11":"product_tag-rf-end-cn7m-gate-valve","13":"first","14":"instock","15":"shipping-taxable","16":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/product\/18142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/media\/18143"}],"wp:attachment":[{"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/media?parent=18142"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/product_brand?post=18142"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/product_cat?post=18142"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/oudianvalve.com\/es\/wp-json\/wp\/v2\/product_tag?post=18142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}